{"id":36340,"date":"2021-05-02T21:48:59","date_gmt":"2021-05-02T18:48:59","guid":{"rendered":"https:\/\/seacare.com\/it\/?page_id=36340"},"modified":"2022-02-14T13:07:11","modified_gmt":"2022-02-14T10:07:11","slug":"effetti-del-mar-morto","status":"publish","type":"page","link":"https:\/\/seacare.com\/it\/effetti-del-mar-morto\/","title":{"rendered":"Effetti del Mar Morto"},"content":{"rendered":"<div class=\"row\"  id=\"row-476409256\">\n<div class=\"col small-12 large-12\"  ><div class=\"col-inner text-center\"  >\n<h1 class=\"text-head\"><span style=\"font-size: 130%; color: #4f4f4f;\" data-text-color=\"Black\">Effetti del Mar Morto<\/span><\/h1>\n<\/div><\/div>\n<\/div>\n<div class=\"row\"  id=\"row-1308746500\">\n<div class=\"col hide-for-medium medium-2 small-12 large-2\"  ><div class=\"col-inner\"  >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1600176317\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u042d\u0444\u0444\u0435\u043a\u0442\u044b-\u043c\u0435\u0440\u0442\u0432\u043e\u0433\u043e-\u043c\u043e\u0440\u044f-\u043a\u0430\u0440\u0442\u0438\u043d\u043a\u0438-\u043a\u043e\u043f\u0438\u044f-1.jpg\" class=\"attachment-large size-large\" alt=\"The effects of the dead sea\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col hide-for-medium medium-8 small-12 large-8\"  ><div class=\"col-inner text-left\" style=\"padding:0px 0px 0px 0px;margin:-19px 0px -37px 0px;\" >\n<p>Le propriet\u00e0 curative del Mar Morto sono note da millenni \u00e8 ricco di sali e un&#8217;abbondanza dei minerali come magnesio, calcio, potassio e bromo. Secondo uno studio del Dott. Zeev Ma&#8217;or effettuato in collaborazione con i colleghi del Centro di ricerca sul Mar Morto in Israele pubblicato nel maggio 2006 sul \u201cGiornale internazionale di dermatologia\u201d il Mar Morto situato nella Grande Fossa Tettonica \u00e8 stato a lungo una fonte di ingredienti per la produzione di vari prodotti per curare e lenire la pelle infiammata.<\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1602959111\">\n<div class=\"col show-for-medium hide-for-small medium-2 small-12 large-2\"  ><div class=\"col-inner\" style=\"margin:26px 0px 0px 0px;\" >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1166207824\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u042d\u0444\u0444\u0435\u043a\u0442\u044b-\u043c\u0435\u0440\u0442\u0432\u043e\u0433\u043e-\u043c\u043e\u0440\u044f-\u043a\u0430\u0440\u0442\u0438\u043d\u043a\u0438-\u043a\u043e\u043f\u0438\u044f-1.jpg\" class=\"attachment-large size-large\" alt=\"The effects of the dead sea\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col show-for-medium hide-for-small medium-8 small-12 large-8\"  ><div class=\"col-inner text-left\" style=\"padding:0px 0px 0px 0px;margin:-19px 0px -37px 0px;\" >\n<p><span style=\"font-size: 105%;\">Le propriet\u00e0 curative del Mar Morto sono note da millenni \u00e8 ricco di sali e un&#8217;abbondanza dei minerali come magnesio, calcio, potassio e bromo. Secondo uno studio del Dott. Zeev Ma&#8217;or effettuato in collaborazione con i colleghi del Centro di ricerca sul Mar Morto in Israele pubblicato nel maggio 2006 sul \u201cGiornale internazionale di dermatologia\u201d il Mar Morto situato nella Grande Fossa Tettonica \u00e8 stato a lungo una fonte di ingredienti per la produzione di vari prodotti per curare e lenire la pelle infiammata.<\/span><\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1152779224\">\n<div class=\"col show-for-small medium-2 small-12 large-2\"  ><div class=\"col-inner\"  >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1989919178\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u042d\u0444\u0444\u0435\u043a\u0442\u044b-\u043c\u0435\u0440\u0442\u0432\u043e\u0433\u043e-\u043c\u043e\u0440\u044f-\u043a\u0430\u0440\u0442\u0438\u043d\u043a\u0438-\u043a\u043e\u043f\u0438\u044f-1.jpg\" class=\"attachment-large size-large\" alt=\"The effects of the dead sea\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col show-for-small medium-8 small-12 large-8\"  ><div class=\"col-inner text-left\" style=\"padding:0px 0px 0px 0px;margin:-19px 0px -37px 0px;\" >\n<p><span style=\"font-size: 105%;\">Le propriet\u00e0 curative del Mar Morto sono note da millenni \u00e8 ricco di sali e un&#8217;abbondanza dei minerali come magnesio, calcio, potassio e bromo. Secondo uno studio del Dott. Zeev Ma&#8217;or effettuato in collaborazione con i colleghi del Centro di ricerca sul Mar Morto in Israele pubblicato nel maggio 2006 sul \u201cGiornale internazionale di dermatologia\u201d il Mar Morto situato nella Grande Fossa Tettonica \u00e8 stato a lungo una fonte di ingredienti per la produzione di vari prodotti per curare e lenire la pelle infiammata.<\/span><\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1825314121\">\n<div class=\"col small-12 large-12\"  ><div class=\"col-inner text-center\" style=\"padding:0px 0px 0px 0px;margin:19px 0px -3px 0px;\" >\n<p><span style=\"font-size: 150%; color: #4f4f4f;\" data-text-color=\"black\"><strong>Propriet\u00e0 antinfiammatorie<\/strong><\/span><\/p>\n<\/div><\/div>\n<\/div>\n<div class=\"row\"  id=\"row-889481198\">\n<div class=\"col hide-for-medium medium-2 small-12 large-2\"  ><div class=\"col-inner\"  >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1382916476\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u0412\u043e\u0441\u043f\u0430\u043b\u0435\u043d\u0438\u0435.jpg\" class=\"attachment-large size-large\" alt=\"Inflammation\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col hide-for-medium medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-42px 0px 0px 0px;\" >\n<p>L&#8217;efficacia dei minerali del Mar Morto \u00e8 stata dimostrata nella terapia di malattie infiammatorie della pelle come la psoriasi. I risultati raggiunti mostrano un notevole miglioramento dei sintomi dopo un solo bagno nell&#8217;acqua del Mar Morto (studio del Dott. Ehrhardt Proksch e colleghi della cattedra di dermatologia dell\u2019Universit\u00e0 di Kiel in Germania, pubblicato nel febbraio 2005 sul \u201cGiornale internazionale di dermatologia\u201d). Secondo la ricerca del Dott. Proksch, il magnesio uno dei principali minerali del Mar Morto blocca la formazione di cellule che contribuiscono alle reazioni allergiche, il fatto che spiega gli effetti antinfiammatori e lenitivi del Mar Morto.<\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-743924098\">\n<div class=\"col show-for-medium hide-for-small medium-2 small-12 large-2\"  ><div class=\"col-inner\" style=\"margin:46px 0px 0px 0px;\" >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_692799982\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u0412\u043e\u0441\u043f\u0430\u043b\u0435\u043d\u0438\u0435.jpg\" class=\"attachment-large size-large\" alt=\"Inflammation\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col show-for-medium hide-for-small medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-42px 0px 0px 0px;\" >\n<p><span style=\"font-size: 105%;\">L&#8217;efficacia dei minerali del Mar Morto \u00e8 stata dimostrata nella terapia di malattie infiammatorie della pelle come la psoriasi. I risultati raggiunti mostrano un notevole miglioramento dei sintomi dopo un solo bagno nell&#8217;acqua del Mar Morto (studio del Dott. Ehrhardt Proksch e colleghi della cattedra di dermatologia dell\u2019Universit\u00e0 di Kiel in Germania, pubblicato nel febbraio 2005 sul \u201cGiornale internazionale di dermatologia\u201d). Secondo la ricerca del Dott. Proksch, il magnesio uno dei principali minerali del Mar Morto blocca la formazione di cellule che contribuiscono alle reazioni allergiche, il fatto che spiega gli effetti antinfiammatori e lenitivi del Mar Morto.<\/span><\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1445097103\">\n<div class=\"col show-for-small medium-2 small-12 large-2\"  ><div class=\"col-inner\" style=\"margin:-26px 0px 0px 0px;\" >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_327656039\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u0412\u043e\u0441\u043f\u0430\u043b\u0435\u043d\u0438\u0435.jpg\" class=\"attachment-large size-large\" alt=\"Inflammation\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col show-for-small medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-17px 0px 0px 0px;\" >\n<p><span style=\"font-size: 105%;\">L&#8217;efficacia dei minerali del Mar Morto \u00e8 stata dimostrata nella terapia di malattie infiammatorie della pelle come la psoriasi. I risultati raggiunti mostrano un notevole miglioramento dei sintomi dopo un solo bagno nell&#8217;acqua del Mar Morto (studio del Dott. Ehrhardt Proksch e colleghi della cattedra di dermatologia dell\u2019Universit\u00e0 di Kiel in Germania, pubblicato nel febbraio 2005 sul \u201cGiornale internazionale di dermatologia\u201d). Secondo la ricerca del Dott. Proksch, il magnesio uno dei principali minerali del Mar Morto blocca la formazione di cellule che contribuiscono alle reazioni allergiche, il fatto che spiega gli effetti antinfiammatori e lenitivi del Mar Morto.<\/span><\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1939336037\">\n<div class=\"col small-12 large-12\"  ><div class=\"col-inner text-center\"  >\n<p><span style=\"font-size: 150%; color: #4f4f4f;\" data-text-color=\"black\"><strong>Uniformazione della tonicit\u00e0 della pelle<\/strong><\/span><\/p>\n<\/div><\/div>\n<\/div>\n<div class=\"row\"  id=\"row-1117482973\">\n<div class=\"col hide-for-medium medium-2 small-12 large-2\"  ><div class=\"col-inner\"  >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1166233607\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u0432\u043e\u0441\u043f\u0430\u043b.jpg\" class=\"attachment-large size-large\" alt=\"inflammation\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col hide-for-medium medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-42px 0px 0px 0px;\" >\n<p>I minerali del Mar Morto, in particolare il magnesio, aumentano il livello di idratazione e di liscezza della pelle, secondo il \u201cGiornale internazionale di dermatologia\u201d. Dopo aver immerso gli avambracci in una soluzione al 5% di acqua del Mar Morto i volontari con la pelle secca hanno sentito l&#8217;effetto di liscezza e l\u2019idratazione. Gli avambracci di altri volontari sono stati immersi nell&#8217;acqua del rubinetto; non hanno sentito alcun effetto simile. Secondo il dott. Proksch, una soluzione minerale del Mar Morto all&#8217;1% applicata due volte al giorno per quattro settimane riduce circa al 41% la ruvidit\u00e0 della pelle, mentre un gel liquido privo di minerali riduce circa al 28% la ruvidit\u00e0 della pelle di.<\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1546720450\">\n<div class=\"col show-for-medium hide-for-small medium-2 small-12 large-2\"  ><div class=\"col-inner\" style=\"margin:49px 0px 0px 0px;\" >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_235944122\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u0432\u043e\u0441\u043f\u0430\u043b.jpg\" class=\"attachment-large size-large\" alt=\"inflammation\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col show-for-medium hide-for-small medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-42px 0px 0px 0px;\" >\n<p><span style=\"font-size: 105%;\">I minerali del Mar Morto, in particolare il magnesio, aumentano il livello di idratazione e di liscezza della pelle, secondo il \u201cGiornale internazionale di dermatologia\u201d. Dopo aver immerso gli avambracci in una soluzione al 5% di acqua del Mar Morto i volontari con la pelle secca hanno sentito l&#8217;effetto di liscezza e l\u2019idratazione. Gli avambracci di altri volontari sono stati immersi nell&#8217;acqua del rubinetto; non hanno sentito alcun effetto simile. Secondo il dott. Proksch, una soluzione minerale del Mar Morto all&#8217;1% applicata due volte al giorno per quattro settimane riduce circa al 41% la ruvidit\u00e0 della pelle, mentre un gel liquido privo di minerali riduce circa al 28% la ruvidit\u00e0 della pelle di.<\/span><\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-367268748\">\n<div class=\"col show-for-small medium-2 small-12 large-2\"  ><div class=\"col-inner\" style=\"padding:0px 0px 0px 0px;margin:-24px 0px 0px 0px;\" >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_752019297\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u0432\u043e\u0441\u043f\u0430\u043b.jpg\" class=\"attachment-large size-large\" alt=\"inflammation\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col show-for-small medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-17px 0px 0px 0px;\" >\n<p><span style=\"font-size: 105%;\">I minerali del Mar Morto, in particolare il magnesio, aumentano il livello di idratazione e di liscezza della pelle, secondo il \u201cGiornale internazionale di dermatologia\u201d. Dopo aver immerso gli avambracci in una soluzione al 5% di acqua del Mar Morto i volontari con la pelle secca hanno sentito l&#8217;effetto di liscezza e l\u2019idratazione. Gli avambracci di altri volontari sono stati immersi nell&#8217;acqua del rubinetto; non hanno sentito alcun effetto simile. Secondo il dott. Proksch, una soluzione minerale del Mar Morto all&#8217;1% applicata due volte al giorno per quattro settimane riduce circa al 41% la ruvidit\u00e0 della pelle, mentre un gel liquido privo di minerali riduce circa al 28% la ruvidit\u00e0 della pelle di.<\/span><\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-2058149235\">\n<div class=\"col small-12 large-12\"  ><div class=\"col-inner text-center\" style=\"margin:5px 0px -36px 0px;\" >\n<p><span style=\"font-size: 150%; color: #4f4f4f;\" data-text-color=\"black\"><strong>Propriet\u00e0 antibatteriche<\/strong><\/span><\/p>\n<\/div><\/div>\n<\/div>\n<div class=\"row\"  id=\"row-1474546445\">\n<div class=\"col hide-for-medium medium-2 small-12 large-2\"  ><div class=\"col-inner\"  >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1088871146\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u0420\u0443\u043a\u0438-\u043a\u043e\u043f\u0438\u044f.jpg\" class=\"attachment-medium size-medium\" alt=\"Arms\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col hide-for-medium medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-11px 0px 0px 0px;\" >\n<p>\u00c8 stato provato che il fango nero ricco di minerali estratto sulle rive del Mar Morto e utilizzato per le maschere e trattamenti termali ha un bassissimo contenuto di batteri e possiede delle propriet\u00e0 antimicrobiche (ricerca del Dott. Ma&#8217;or). Le propriet\u00e0 antibatteriche del fango del Mar Morto sono in parte dovute all&#8217;alto contenuto di sale e solfuri, cos\u00ec si spiega l&#8217;effetto anti-acne delle maschere per il viso a base del fango del Mar Morto, afferma il dott. Ma&#8217;or.<\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-918119491\">\n<div class=\"col show-for-medium hide-for-small medium-2 small-12 large-2\"  ><div class=\"col-inner\" style=\"margin:37px 0px 0px 0px;\" >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1128993343\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u0420\u0443\u043a\u0438-\u043a\u043e\u043f\u0438\u044f.jpg\" class=\"attachment-medium size-medium\" alt=\"Arms\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col show-for-medium hide-for-small medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-11px 0px 0px 0px;\" >\n<p><span style=\"font-size: 105%;\">\u00c8 stato provato che il fango nero ricco di minerali estratto sulle rive del Mar Morto e utilizzato per le maschere e trattamenti termali ha un bassissimo contenuto di batteri e possiede delle propriet\u00e0 antimicrobiche (ricerca del Dott. Ma&#8217;or). Le propriet\u00e0 antibatteriche del fango del Mar Morto sono in parte dovute all&#8217;alto contenuto di sale e solfuri, cos\u00ec si spiega l&#8217;effetto anti-acne delle maschere per il viso a base del fango del Mar Morto, afferma il dott. Ma&#8217;or.<\/span><\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1056298428\">\n<div class=\"col show-for-small medium-2 small-12 large-2\"  ><div class=\"col-inner\" style=\"margin:6px 0px 0px 0px;\" >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1809902953\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u0420\u0443\u043a\u0438-\u043a\u043e\u043f\u0438\u044f.jpg\" class=\"attachment-medium size-medium\" alt=\"Arms\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col show-for-small medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-19px 0px 0px 0px;\" >\n<p><span style=\"font-size: 105%;\">\u00c8 stato provato che il fango nero ricco di minerali estratto sulle rive del Mar Morto e utilizzato per le maschere e trattamenti termali ha un bassissimo contenuto di batteri e possiede delle propriet\u00e0 antimicrobiche (ricerca del Dott. Ma&#8217;or). Le propriet\u00e0 antibatteriche del fango del Mar Morto sono in parte dovute all&#8217;alto contenuto di sale e solfuri, cos\u00ec si spiega l&#8217;effetto anti-acne delle maschere per il viso a base del fango del Mar Morto, afferma il dott. Ma&#8217;or.<\/span><\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1376685606\">\n<div class=\"col small-12 large-12\"  ><div class=\"col-inner text-center\" style=\"margin:1px 0px -13px 0px;\" >\n<p><span style=\"font-size: 150%; color: #4f4f4f;\" data-text-color=\"Black\"><strong>Fonti<\/strong><\/span><\/p>\n<\/div><\/div>\n<\/div>\n<div class=\"row\"  id=\"row-986950095\">\n<div class=\"col hide-for-medium medium-2 small-12 large-2\"  ><div class=\"col-inner\"  >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_777711937\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u041a\u043d\u0438\u0433\u0438.jpg\" class=\"attachment-medium size-medium\" alt=\"\u041a\u043d\u0438\u0433\u0438\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col hide-for-medium medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-30px 0px 0px 0px;\" >\n<p class=\"o-kom-punkt\"><span style=\"font-size: 105%;\"><img decoding=\"async\" class=\"marker\" src=\"\/wp-content\/uploads\/2013\/08\/punkt.png\" \/>&#8220;Giornale internazionale di dermatologia\u201d: propriet\u00e0 antimicrobiche del fango minerale nero del Mar Morto; Dr. Z. Ma&#8217;or; Maggio 2006 <\/span><br \/>\n<span style=\"font-size: 105%;\"><img decoding=\"async\" class=\"marker\" src=\"\/wp-content\/uploads\/2013\/08\/punkt.png\" \/>&#8220;Giornale internazionale di dermatologia\u201d: Il bagno in una soluzione di sale del Mar Morto arricchita con magnesio migliora la funzione protettiva della pelle, aumenta l&#8217;idratazione della pelle e riduce l&#8217;infiammazione della pelle secca; Dott. E. Proksch; Febbraio 2005<\/span><br \/>\n<span style=\"font-size: 105%;\"><img decoding=\"async\" class=\"marker\" src=\"\/wp-content\/uploads\/2013\/08\/punkt.png\" \/>&#8220;Giornale internazionale di dermatologia\u201d: Uniformazione della tonicit\u00e0 della pelle con i minerali del Mar Morto: Confronto e valutazione della superficie della pelle; Dott. Z. Ma&#8217;or; Giugno 1997 <\/span><\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-251846211\">\n<div class=\"col show-for-medium hide-for-small medium-2 small-12 large-2\"  ><div class=\"col-inner\" style=\"margin:61px 0px 0px 0px;\" >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1164451992\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u041a\u043d\u0438\u0433\u0438.jpg\" class=\"attachment-medium size-medium\" alt=\"\u041a\u043d\u0438\u0433\u0438\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col show-for-medium hide-for-small medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-30px 0px 0px 0px;\" >\n<p class=\"o-kom-punkt\"><span style=\"font-size: 105%;\"><img decoding=\"async\" class=\"marker\" src=\"\/wp-content\/uploads\/2013\/08\/punkt.png\" \/>&#8220;Giornale internazionale di dermatologia\u201d: propriet\u00e0 antimicrobiche del fango minerale nero del Mar Morto; Dr. Z. Ma&#8217;or; Maggio 2006 <\/span><br \/>\n<span style=\"font-size: 105%;\"><img decoding=\"async\" class=\"marker\" src=\"\/wp-content\/uploads\/2013\/08\/punkt.png\" \/>&#8220;Giornale internazionale di dermatologia\u201d: Il bagno in una soluzione di sale del Mar Morto arricchita con magnesio migliora la funzione protettiva della pelle, aumenta l&#8217;idratazione della pelle e riduce l&#8217;infiammazione della pelle secca; Dott. E. Proksch; Febbraio 2005<\/span><br \/>\n<span style=\"font-size: 105%;\"><img decoding=\"async\" class=\"marker\" src=\"\/wp-content\/uploads\/2013\/08\/punkt.png\" \/>&#8220;Giornale internazionale di dermatologia\u201d: Uniformazione della tonicit\u00e0 della pelle con i minerali del Mar Morto: Confronto e valutazione della superficie della pelle; Dott. Z. Ma&#8217;or; Giugno 1997 <\/span><\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1586088946\">\n<div class=\"col show-for-small medium-2 small-12 large-2\"  ><div class=\"col-inner\" style=\"margin:-15px 0px 0px 0px;\" >\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_371016481\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"156\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u041a\u043d\u0438\u0433\u0438.jpg\" class=\"attachment-medium size-medium\" alt=\"\u041a\u043d\u0438\u0433\u0438\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n<\/div><\/div>\n<div class=\"col show-for-small medium-8 small-12 large-8\"  ><div class=\"col-inner\" style=\"margin:-17px 0px 0px 0px;\" >\n<p class=\"o-kom-punkt\"><span style=\"font-size: 105%;\"><img decoding=\"async\" class=\"marker\" src=\"\/wp-content\/uploads\/2013\/08\/punkt.png\" \/>&#8220;Giornale internazionale di dermatologia\u201d: propriet\u00e0 antimicrobiche del fango minerale nero del Mar Morto; Dr. Z. Ma&#8217;or; Maggio 2006 <\/span><br \/>\n<span style=\"font-size: 105%;\"><img decoding=\"async\" class=\"marker\" src=\"\/wp-content\/uploads\/2013\/08\/punkt.png\" \/>&#8220;Giornale internazionale di dermatologia\u201d: Il bagno in una soluzione di sale del Mar Morto arricchita con magnesio migliora la funzione protettiva della pelle, aumenta l&#8217;idratazione della pelle e riduce l&#8217;infiammazione della pelle secca; Dott. E. Proksch; Febbraio 2005<\/span><br \/>\n<span style=\"font-size: 105%;\"><img decoding=\"async\" class=\"marker\" src=\"\/wp-content\/uploads\/2013\/08\/punkt.png\" \/>&#8220;Giornale internazionale di dermatologia\u201d: Uniformazione della tonicit\u00e0 della pelle con i minerali del Mar Morto: Confronto e valutazione della superficie della pelle; Dott. Z. Ma&#8217;or; Giugno 1997 <\/span><\/p>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1023923128\">\n                <div class=\"img-inner dark\" >\n        <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"95\" src=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u041b\u043e\u0433\u043e\u0442\u0438\u043f-\u0434\u043b\u044f-\u0421\u0430\u0438\u0306\u0442\u0430-SeaCare-\u043a\u043e\u043f\u0438\u044f-1400x130.png\" class=\"attachment-large size-large\" alt=\"Logo for the SeaCare Website\" srcset=\"https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u041b\u043e\u0433\u043e\u0442\u0438\u043f-\u0434\u043b\u044f-\u0421\u0430\u0438\u0306\u0442\u0430-SeaCare-\u043a\u043e\u043f\u0438\u044f-1400x130.png 1400w, https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u041b\u043e\u0433\u043e\u0442\u0438\u043f-\u0434\u043b\u044f-\u0421\u0430\u0438\u0306\u0442\u0430-SeaCare-\u043a\u043e\u043f\u0438\u044f-800x74.png 800w, https:\/\/seacare.com\/wp-content\/uploads\/2020\/10\/\u041b\u043e\u0433\u043e\u0442\u0438\u043f-\u0434\u043b\u044f-\u0421\u0430\u0438\u0306\u0442\u0430-SeaCare-\u043a\u043e\u043f\u0438\u044f-768x71.png 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>                \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n    <div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_617876233\">\n                <div class=\"img-inner dark\" >\n                        \n            <\/div>\n                   \n<style scope=\"scope\">\n\n<\/style>\n    <\/div>\n    \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/seacare.com\/it\/wp-json\/wp\/v2\/pages\/36340"}],"collection":[{"href":"https:\/\/seacare.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seacare.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seacare.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/seacare.com\/it\/wp-json\/wp\/v2\/comments?post=36340"}],"version-history":[{"count":5,"href":"https:\/\/seacare.com\/it\/wp-json\/wp\/v2\/pages\/36340\/revisions"}],"predecessor-version":[{"id":55442,"href":"https:\/\/seacare.com\/it\/wp-json\/wp\/v2\/pages\/36340\/revisions\/55442"}],"wp:attachment":[{"href":"https:\/\/seacare.com\/it\/wp-json\/wp\/v2\/media?parent=36340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}